

	{"id":16034,"date":"2024-09-05T22:00:06","date_gmt":"2024-09-06T01:00:06","guid":{"rendered":"https:\/\/www.cstuit.com\/home\/?p=16034"},"modified":"2024-09-05T22:00:06","modified_gmt":"2024-09-06T01:00:06","slug":"a-cisjordania-sera-o-segundo-tumulo-do-sionismo","status":"publish","type":"post","link":"https:\/\/www.cstuit.com\/home\/2024\/09\/05\/a-cisjordania-sera-o-segundo-tumulo-do-sionismo\/","title":{"rendered":"A Cisjord\u00e2nia ser\u00e1 o segundo t\u00famulo do sionismo"},"content":{"rendered":"<p><em>Por: Partido da Democracia Oper\u00e1ria (IDP), se\u00e7\u00e3o da UIT-QI na Turquia<\/em><\/p>\n<p>No dia 28 de agosto de 2024, o Estado de ocupa\u00e7\u00e3o sionista lan\u00e7ou uma ampla opera\u00e7\u00e3o militar visando as cidades e acampamentos do norte da Cisjord\u00e2nia (Jenin, Tubas, Tulkarem, Al Khalil e Ramallah), que pretende anexar completamente tais territ\u00f3rios. Essa opera\u00e7\u00e3o militar, que \u00e9 a maior tentativa de ocupa\u00e7\u00e3o da Cisjord\u00e2nia desde 2002, \u00e9 uma amplia\u00e7\u00e3o direta do genoc\u00eddio sangrento e criminoso que o sionismo tem levado a cabo contra o povo palestino em Gaza h\u00e1 11 meses. O objetivo dessa agress\u00e3o \u00e9 ocupar completamente a Cisjord\u00e2nia, destruir a resist\u00eancia, aprofundar a guerra existencial travada contra o povo palestino pela alian\u00e7a do imperialismo e do sionismo e tentar mudar a situa\u00e7\u00e3o militar na regi\u00e3o a favor das for\u00e7as ocupantes, uma vez que Israel n\u00e3o alcan\u00e7ou nenhum dos seus objetivos em Gaza.<\/p>\n<p>Essa tentativa de ocupa\u00e7\u00e3o \u00e9 tamb\u00e9m uma ferramenta do sionismo para implementar os seus planos racistas e colonialistas recentemente anunciados: com a agress\u00e3o pretende-se estabelecer o controle sionista absoluto sobre Al Quds, a capital da Palestina, e Al-Aqsa, que \u00e9 sagrada tanto para mu\u00e7ulmanos quanto para crist\u00e3os; e mudar a estrutura demogr\u00e1fica e social da Cisjord\u00e2nia, acelerando o processo de \u201cjudaiza\u00e7\u00e3o\u201d atrav\u00e9s dos colonos. Os ministros racistas sionistas, Katz e Smotrich, declararam abertamente que querem anexar toda a Cisjord\u00e2nia e que uma sinagoga deveria ser aberta no p\u00e1tio da mesquita de Al-Aqsa.<\/p>\n<p>Como parte da opera\u00e7\u00e3o militar, as for\u00e7as de ocupa\u00e7\u00e3o sionistas bloquearam hospitais na Cisjord\u00e2nia, impediram que os feridos recebessem tratamento e que ambul\u00e2ncias circulassem. Impuseram um embargo a cidades, com centenas de soldados e ve\u00edculos blindados, e atacaram casas de palestinos com avi\u00f5es de guerra e drones. O Estado sionista, que utilizava o seu poder a\u00e9reo apenas contra a resist\u00eancia em Gaza, come\u00e7ou a bombardear a resist\u00eancia na Cisjord\u00e2nia com os seus avi\u00f5es de guerra e drones h\u00e1 algumas semanas, \u00e0 medida que as opera\u00e7\u00f5es da resist\u00eancia na Cisjord\u00e2nia aumentavam e se tornavam mais qualificadas. Essa nova situa\u00e7\u00e3o foi uma express\u00e3o do decl\u00ednio da capacidade militar do Estado de ocupa\u00e7\u00e3o racista contra a resist\u00eancia na Cisjord\u00e2nia.<\/p>\n<p>Segundo um estudo publicado pelo Centro de Investiga\u00e7\u00e3o Mo&#8217;ta no final de julho, a resist\u00eancia Palestina realizou 2.444 opera\u00e7\u00f5es militares na Cisjord\u00e2nia desde 7 de outubro de 2023. Dessas, 1.533 foram opera\u00e7\u00f5es com disparos e 678 com explosivos. O Estado ocupante, que esconde as suas baixas, anunciou que perdeu apenas 30 soldados e 310 ficaram feridos nessas opera\u00e7\u00f5es. Jenin, que foi o foco principal da opera\u00e7\u00e3o de ocupa\u00e7\u00e3o integral iniciada em 28 de agosto, destaca-se por acolher 855 dessas 2.444 opera\u00e7\u00f5es da resist\u00eancia, ou seja, 35%.<\/p>\n<p>Embora o n\u00famero de opera\u00e7\u00f5es da resist\u00eancia seja o mencionado, o n\u00famero de incidentes anunciados pelo Centro de Investiga\u00e7\u00e3o Mo&#8217;ta sob o t\u00edtulo de \u201cconflito\u201d para o mesmo per\u00edodo \u00e9 de 3.771. Apesar de 734 deles terem sido realizados na forma de mobiliza\u00e7\u00f5es de massa, sabe-se que ocorreram 125 ataques com coquet\u00e9is molotov.<\/p>\n<p>Essa onda de lutas do povo palestino e da resist\u00eancia na Cisjord\u00e2nia mereceria, sem d\u00favida, ser chamada de Terceira Intifada, se n\u00e3o fosse o genoc\u00eddio que est\u00e1 ocorrendo em Gaza e a luta contra o mesmo. O Estado sionista interpretou a situa\u00e7\u00e3o na Cisjord\u00e2nia exatamente dessa forma. Desde 7 de outubro de 2023, massacrou 585 palestinos naquela regi\u00e3o, feriu 3.735 e sequestrou 9.860. A tentativa de ocupa\u00e7\u00e3o lan\u00e7ada em 28 de agosto n\u00e3o visa apenas tentar reverter a situa\u00e7\u00e3o militar na regi\u00e3o e continuar a Nakba de 1948, mas tamb\u00e9m suprimir a Terceira Intifada.<\/p>\n<p>A tentativa de ocupa\u00e7\u00e3o da Cisjord\u00e2nia pelo sionismo come\u00e7ou e continua inteiramente com a coopera\u00e7\u00e3o, aprova\u00e7\u00e3o e apoio dos pa\u00edses imperialistas e com o sil\u00eancio criminoso dos regimes \u00e1rabes capitalistas. A arrog\u00e2ncia do Estado genocida nos seus planos para destruir a na\u00e7\u00e3o palestina e na sua oferta de \u201crendi\u00e7\u00e3o\u201d \u00e0 resist\u00eancia palestina deriva do apoio que recebe do imperialismo e dos regimes \u00e1rabes colaboracionistas.<\/p>\n<p>A Autoridade Palestina e Mahmoud Abbas, seu presidente, que foi recentemente convidado \u00e0 Turquia para discursar na Grande Assembleia Nacional Turca, usaram as for\u00e7as \u00e0 sua disposi\u00e7\u00e3o, desde 7 de outubro de 2023, para assassinar l\u00edderes da resist\u00eancia, sequestrar os seus combatentes nos hospitais e confiscar os arsenais dos grupos de resist\u00eancia. Essa abordagem colaboracionista provocou grande descontentamento e raiva entre o povo palestino da Cisjord\u00e2nia, com mobiliza\u00e7\u00f5es em massa e confrontos para proteger os combatentes da resist\u00eancia nos hospitais dos agentes da pol\u00edcia da Autoridade Palestiniana. A popularidade de Mahmoud Abbas caiu abaixo dos 20% nas pesquisas, enquanto a popularidade de Ismail Haniyeh, que foi assassinado, aproximou-se de 80%.<\/p>\n<p>Diante da tentativa de ocupa\u00e7\u00e3o da Cisjord\u00e2nia iniciada em 28 de agosto, a Autoridade Palestina, sob a lideran\u00e7a de Mahmoud Abbas, deve abandonar a sua antiga linha colaboracionista; acabar com a troca de informa\u00e7\u00f5es com o inimigo sionista; adoptar uma posi\u00e7\u00e3o de apoio \u00e0 vontade e \u00e0 resist\u00eancia do povo palestino; optar pela restaura\u00e7\u00e3o da unidade nacional, expressa na Declara\u00e7\u00e3o de Pequim; e construir uma reuni\u00e3o unificada destinada a estabelecer um governo de consenso nacional-revolucion\u00e1rio. Os planos divisionistas do governo sionista, que procura separar Gaza da Cisjord\u00e2nia com o genoc\u00eddio e a ocupa\u00e7\u00e3o, devem ser frustrados com um programa de a\u00e7\u00e3o nacional unit\u00e1rio.<\/p>\n<p>N\u00f3s, do Partido da Democracia Oper\u00e1ria (IDP) da Turquia, expressamos mais uma vez o nosso apoio \u00e0 Resist\u00eancia Palestina, contra o genoc\u00eddio e a ocupa\u00e7\u00e3o em curso em Gaza e na Cisjord\u00e2nia, e \u00e0 luta do povo palestino para regressar e determinar o seu pr\u00f3prio destino.<\/p>\n<p>O Estado sionista est\u00e1 cometendo crimes de guerra tanto em Gaza como na Cisjord\u00e2nia e deve, portanto, ser submetido a um julgamento exaustivo.<\/p>\n<p>Os regimes colaboracionistas da regi\u00e3o, incluindo o regime turco, devem p\u00f4r fim a todas as rela\u00e7\u00f5es econ\u00f4micas, comerciais e diplom\u00e1ticas com o Estado genocida sionista.<\/p>\n<p>Para parar o genoc\u00eddio em Gaza e a ocupa\u00e7\u00e3o na Cisjord\u00e2nia, e apoiar a vit\u00f3ria da Resist\u00eancia Palestina, apelamos \u00e0s massas para que se mobilizem contra os governos colaboracionistas nos seus pr\u00f3prios pa\u00edses. E declaramos que a mobiliza\u00e7\u00e3o \u00e9 necess\u00e1ria at\u00e9 que termine o genoc\u00eddio em Gaza e a ocupa\u00e7\u00e3o na Cisjord\u00e2nia.<\/p>\n<p>Pelo fim do genoc\u00eddio em Gaza!<\/p>\n<p>N\u00e3o \u00e0 anexa\u00e7\u00e3o da Cisjord\u00e2nia!<\/p>\n<p>Mobilizar contra a ocupa\u00e7\u00e3o da Cisjord\u00e2nia!<\/p>\n<p>A Nakba continua: n\u00e3o a uma nova Nakba!<\/p>\n<p>Pelo fim imediato de todas as rela\u00e7\u00f5es com o Estado sionista! Pelo fechamento imediato das v\u00e1lvulas que despejam petr\u00f3leo no Estado sionista!<\/p>\n<p>Do rio ao mar, a Palestina ser\u00e1 livre!<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Por: Partido da Democracia Oper\u00e1ria (IDP), se\u00e7\u00e3o da UIT-QI na Turquia No dia 28 de agosto de 2024, o Estado de ocupa\u00e7\u00e3o sionista lan\u00e7ou uma ampla opera\u00e7\u00e3o militar visando as cidades e acampamentos do norte da Cisjord\u00e2nia (Jenin, Tubas, Tulkarem, Al Khalil e Ramallah), que<\/p>\n","protected":false},"author":1,"featured_media":16035,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[6],"tags":[2332,1981,473,251,1818,2139,2067,223,1275,300,2333,131],"class_list":["post-16034","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-internacional","tag-cisjordania","tag-crimes","tag-gaza","tag-genocidio","tag-idp","tag-livre","tag-nakba","tag-palestina","tag-petroleo","tag-sionismo","tag-sionistas","tag-turquia"],"_links":{"self":[{"href":"https:\/\/www.cstuit.com\/home\/wp-json\/wp\/v2\/posts\/16034","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.cstuit.com\/home\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cstuit.com\/home\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cstuit.com\/home\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cstuit.com\/home\/wp-json\/wp\/v2\/comments?post=16034"}],"version-history":[{"count":0,"href":"https:\/\/www.cstuit.com\/home\/wp-json\/wp\/v2\/posts\/16034\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.cstuit.com\/home\/wp-json\/wp\/v2\/media\/16035"}],"wp:attachment":[{"href":"https:\/\/www.cstuit.com\/home\/wp-json\/wp\/v2\/media?parent=16034"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cstuit.com\/home\/wp-json\/wp\/v2\/categories?post=16034"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cstuit.com\/home\/wp-json\/wp\/v2\/tags?post=16034"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}