

	{"id":16544,"date":"2024-12-08T21:13:33","date_gmt":"2024-12-09T00:13:33","guid":{"rendered":"https:\/\/www.cstuit.com\/home\/?p=16544"},"modified":"2024-12-08T21:13:33","modified_gmt":"2024-12-09T00:13:33","slug":"educacao-e-lutas-em-minas-gerais","status":"publish","type":"post","link":"https:\/\/www.cstuit.com\/home\/2024\/12\/08\/educacao-e-lutas-em-minas-gerais\/","title":{"rendered":"Educa\u00e7\u00e3o e lutas em Minas Gerais"},"content":{"rendered":"<h3>Construir gr\u00eamios combativos e independentes<\/h3>\n<p><em>Secundaristas Vamos \u00e0 Luta &#8211; Uberl\u00e2ndia<\/em><\/p>\n<p>A situa\u00e7\u00e3o da juventude trabalhadora n\u00e3o \u00e9 f\u00e1cil. Trabalha em empregos prec\u00e1rios, com baixos sal\u00e1rios, sem direitos e em jornadas 6&#215;1. E no cotidiano escolar enfrenta o nefasto Novo Ensino M\u00e9dio (NEM). Para a Juventude Vamos \u00e0 Luta \u00e9 poss\u00edvel mudar esta dura realidade. A constru\u00e7\u00e3o de gr\u00eamios estudantis de luta \u00e9 fundamental no avan\u00e7o da organiza\u00e7\u00e3o estudantil. \u00c9 necess\u00e1rio resgatar o papel hist\u00f3rico que o movimento secundarista j\u00e1 cumpriu, como aconteceu na derrubada da ditadura, nas ocupa\u00e7\u00f5es de 2016 contra o fechamento de\u00a0escolas, nas lutas pelo passe livre e contra o projeto Escola Sem Partido. S\u00f3 com luta nas ruas conseguiremos derrubar o NEM, as parcerias p\u00fablico-privadas &#8211; defendidas pelo governo Lula &#8211; que abrem espa\u00e7o para as privatiza\u00e7\u00f5es, a militariza\u00e7\u00e3o das escolas, a jornada 6X1 e lutar pelo aumento das bolsas do programa p\u00e9-de-meia e investimento na educa\u00e7\u00e3o p\u00fablica. Por isso, \u00e9 necess\u00e1rio que\u00a0a\u00a0UBES tenha independ\u00eancia pol\u00edtica do governo Lula.\u00a0Infelizmente, a postura da entidade, dirigida pela UJS (PCdoB), juventudes do PT e Levante Popular da Juventude, \u00e9 a passividade. A UBES abandonou a luta pela revoga\u00e7\u00e3o do NEM, n\u00e3o organiza a luta contra as privatiza\u00e7\u00f5es e militariza\u00e7\u00e3o da educa\u00e7\u00e3o p\u00fablica de Tarc\u00edsio e Zema. A juventude Vamos \u00e0 Luta chama os e as estudantes secundas a se somarem conosco para construir gr\u00eamios de luta e exigir que a UBES\u00a0construa\u00a0um calend\u00e1rio de lutas unificadas nacionalmente para enfrentar os ataques dos governos.<\/p>\n<p>&nbsp;<\/p>\n<p><!--more--><\/p>\n<h3>Importante chapa da oposi\u00e7\u00e3o de esquerda no DCE da UFMG<\/h3>\n<p><em>Por Duda Pereira &#8211; Estudante da UFMG e Jeane Carla- Juventude Vamos \u00e0 Luta<\/em><\/p>\n<p>As elei\u00e7\u00f5es para o DCE \u2014 Diret\u00f3rio Central dos Estudantes \u2014 da UFMG ocorreram nos dias 12 e 13\/11. A corrida eleitoral foi disputada por tr\u00eas chapas: Ponta de Lan\u00e7a (Afronte, Correnteza e Juntos), UFMG Vai Virar Baile (Levante) e Primavera nos Dentes &#8211; Oposi\u00e7\u00e3o de Esquerda Unificada (Juventude Vamos \u00e0 Luta, Fa\u00edsca, Rebeldia e UJC). A primeira chapa foi formada por movimentos, como Juntos e Afronte, que compunham a gest\u00e3o anterior e acabou se reelegendo pela terceira vez consecutiva (2.558 votos).<br \/>\nA Juventude Vamos \u00e0 Luta (CST + independentes) marcou presen\u00e7a no processo propondo e realizando uma alian\u00e7a com outros grupos da esquerda independente. Defendemos uma gest\u00e3o de luta, independente de governos, como o governo Lula\/Alckmin, patr\u00f5es e reitorias. Assim, o DCE e movimento estudantil reivindicariam pautas importantes, de fato, para os estudantes, como o fim do Arcabou\u00e7o Fiscal, o fim da FUMP \u2014 Funda\u00e7\u00e3o Universit\u00e1ria Mendes Pimentel \u2014 enquanto assist\u00eancia estudantil privada, a conquista do \u00f4nibus intercampi, al\u00e9m do investimento massivo nas universidades para a perman\u00eancia dos filhos da classe trabalhadora nela.<br \/>\nDe modo tamb\u00e9m autorit\u00e1rio, a reitoria e as dire\u00e7\u00f5es das faculdades e institutos v\u00eam implantando pol\u00edticas de fechamento \u00e0s entidades estudantis. No Instituto de Ci\u00eancias Exatas, todos os Centros e Diret\u00f3rios Acad\u00eamicos foram fechados. Infelizmente, a chapa 4, compondo o DCE (Afronte e Juntos) ainda, n\u00e3o teve uma pol\u00edtica de enfrentamento \u00e0 reitoria. Na Faculdade de Filosofia e Ci\u00eancias Humanas, assinaram um termo que limita suas a\u00e7\u00f5es enquanto movimento estudantil, sendo que o CA de Psicologia foi trancado por n\u00e3o concordar com a medida. Diante disso, a nossa chapa defendeu total independ\u00eancia do DCE e do movimento estudantil frente \u00e0 reitoria para reabrir<br \/>\ntodas as entidades estudantis e organizar a luta contra a atual reitoria.<\/p>\n<p><strong>Pela independ\u00eancia em rela\u00e7\u00e3o aos governos<\/strong><\/p>\n<p>Recentemente, o prefeito Fuad Noman \u2014 reeleito nas \u00faltimas elei\u00e7\u00f5es, com o apoio das organiza\u00e7\u00f5es da chapa 2 (Levante Popular) e da Chapa 1 (Afronte e Juntos), e apoiador da ditadura militar \u2014 decidiu realizar o evento Stock Car ao lado do hospital veterin\u00e1rio da UFMG, sem consult\u00e1-la, derrubando \u00e1rvores e gerando transtornos para a constru\u00e7\u00e3o da pista de corrida. Esse absurdo realizado pelo prefeito n\u00e3o foi barrado pelo DCE, por meio de mobiliza\u00e7\u00f5es independentes para preservar as redondezas da universidade e garantir a perman\u00eancia dos estudantes. Por isso, nossa chapa coloca a necessidade da independ\u00eancia pol\u00edtica em rela\u00e7\u00e3o aos governos. E, desde j\u00e1, se colocou em posi\u00e7\u00e3o n\u00edtida de enfrentamento ao pr\u00f3ximo mandato de Fuad.<br \/>\nFrente a esse cen\u00e1rio, as chapas concorrentes n\u00e3o se posicionaram contra essas situa\u00e7\u00f5es. A Ponta de Lan\u00e7a, por ser composta por movimentos apoiadores da frente ampla, n\u00e3o questiona medidas tomadas pelo governo Lula, como o corte de gastos \u00e0 educa\u00e7\u00e3o. Nas \u00faltimas gest\u00f5es, o DCE veio<br \/>\natuando com nenhuma independ\u00eancia do governo Lula, n\u00e3o construiu de fato a greve estudantil da UFMG contra o Arcabou\u00e7o Fiscal do governo federal, n\u00e3o organizou os estudantes contra a proibi\u00e7\u00e3o de festas no espa\u00e7o universit\u00e1rio, outra medida autorit\u00e1ria da atual reitoria. Do outro lado, a chapa 2, a UFMG Vai Virar Baile, fez uma campanha completamente governista, sem citar o governo Lula, que hoje \u00e9 respons\u00e1vel por todos os cortes nas universidades, estando ausente durante a maior parte da campanha eleitoral. Como resultado, a sua vota\u00e7\u00e3o foi pequena, com apenas 145 votos.<\/p>\n<p><strong>Com a Primavera nos Dentes&#8230;<\/strong><\/p>\n<p>A chapa Primavera nos Dentes \u2014 nome que homenageia a m\u00fasica hom\u00f4nima do Secos e Molhados \u2014 fez uma campanha de muita luta, apesar da atual desmobiliza\u00e7\u00e3o do movimento estudantil \u2014 refletida na disparidade entre os 48.392 eleitores e 3.441 votantes \u2014. A chapa 3 conquistou a<br \/>\nconfian\u00e7a de 738 eleitores. Isso porque defendemos propostas conectadas \u00e0s necessidades dos estudantes da UFMG, apostando nas mobiliza\u00e7\u00f5es como m\u00e9todo para conquistar todas as nossas reivindica\u00e7\u00f5es e sem nenhuma confian\u00e7a nos governos e reitoria.<\/p>\n<p>Agradecemos todos os votos destinados \u00e0 chapa que compusemos, que significam votos de luta. Da nossa parte, vamos seguir fortalecendo o polo da esquerda independente que surgiu nessas elei\u00e7\u00f5es para organizarmos a luta dos estudantes da UFMG. Chamamos voc\u00ea, estudante, a se juntar a n\u00f3s nessa batalha.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Construir gr\u00eamios combativos e independentes Secundaristas Vamos \u00e0 Luta &#8211; Uberl\u00e2ndia A situa\u00e7\u00e3o da juventude trabalhadora n\u00e3o \u00e9 f\u00e1cil. Trabalha em empregos prec\u00e1rios, com baixos sal\u00e1rios, sem direitos e em jornadas 6&#215;1. E no cotidiano escolar enfrenta o nefasto Novo Ensino M\u00e9dio (NEM). Para a<\/p>\n","protected":false},"author":1,"featured_media":12507,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[646,173,1810,2386,726,2169,2172],"class_list":["post-16544","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-juventude","tag-escolas","tag-estudantes","tag-governo","tag-gremios","tag-mg","tag-nem","tag-zema"],"_links":{"self":[{"href":"https:\/\/www.cstuit.com\/home\/wp-json\/wp\/v2\/posts\/16544","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.cstuit.com\/home\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cstuit.com\/home\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cstuit.com\/home\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cstuit.com\/home\/wp-json\/wp\/v2\/comments?post=16544"}],"version-history":[{"count":0,"href":"https:\/\/www.cstuit.com\/home\/wp-json\/wp\/v2\/posts\/16544\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.cstuit.com\/home\/wp-json\/wp\/v2\/media\/12507"}],"wp:attachment":[{"href":"https:\/\/www.cstuit.com\/home\/wp-json\/wp\/v2\/media?parent=16544"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cstuit.com\/home\/wp-json\/wp\/v2\/categories?post=16544"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cstuit.com\/home\/wp-json\/wp\/v2\/tags?post=16544"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}