

	{"id":17305,"date":"2025-06-07T14:22:47","date_gmt":"2025-06-07T17:22:47","guid":{"rendered":"https:\/\/www.cstuit.com\/home\/?p=17305"},"modified":"2025-06-12T14:25:24","modified_gmt":"2025-06-12T17:25:24","slug":"justica-para-herus-mendes","status":"publish","type":"post","link":"https:\/\/www.cstuit.com\/home\/2025\/06\/07\/justica-para-herus-mendes\/","title":{"rendered":"Justi\u00e7a para Herus Mendes"},"content":{"rendered":"<p><strong>Chega da matan\u00e7a da pol\u00edcia<\/strong><\/p>\n<p>O Bope do Rio de Janeiro realizou uma opera\u00e7\u00e3o na comunidade Santo Amaro na Gl\u00f3ria e matou o jovem Herus Guimar\u00e3es Mendes, de 24 anos. Mais uma a\u00e7\u00e3o criminosa da pol\u00edcia do governador da extrema direita, Cl\u00e1udio Castro (PL) que ceifou a vida de um jovem e baleou mais 5 pessoas. \u00c9 o m\u00e9todo do atira primeiro e pergunta depois que tem sido a marca da pol\u00edtica de seguran\u00e7a de Castro.<\/p>\n<p>Como sempre, a narrativa mentirosa contada pela pol\u00edcia \u00e9 a mesma. Foi atacada por criminosos. S\u00f3 n\u00e3o considerou que fazia uma opera\u00e7\u00e3o na comunidade em plena uma festa junina onde muitas pessoas, entre elas v\u00e1rias crian\u00e7as, se divertiam em um momento de lazer.<\/p>\n<p><strong>Claudio Castro tem as m\u00e3os sujas de sangue<\/strong><\/p>\n<p><strong>Fora Cl\u00e1udio Castro e a sua pol\u00edtica de seguran\u00e7a<\/strong><\/p>\n<p>N\u00e3o temos d\u00favida que Cl\u00e1udio Castro est\u00e1 com as m\u00e3os sujas de sangue e que ele e o Secret\u00e1rio de Seguran\u00e7a s\u00e3o os respons\u00e1veis pela morte do jovem Herus. Essa falida pol\u00edtica de seguran\u00e7a p\u00fablica que visa matar pobres e negros tem sido a marca dos governos nos \u00faltimos 40 anos no estado do Rio e est\u00e1 mais claro que s\u00f3 aumenta a viol\u00eancia.<\/p>\n<p>E o Prefeito Eduardo Paes( PSD) apoiando essa mesma falida pol\u00edtica quer armar a guarda municipal o que s\u00f3 vai potencializar ainda mais viol\u00eancia contra os trabalhadores e a popula\u00e7\u00e3o mais vulner\u00e1vel.<\/p>\n<p><strong>Fim da guerra ao povo negro e do exterm\u00ednio da juventude nas favelas<\/strong><\/p>\n<p>Os governadores e a c\u00fapula militar se escondem num discurso de combate \u201cao crime\u201d e numa cruzada contra as \u201cdrogas\u201d. Tudo mentira, pois os maiores criminosos, os milicianos que controlam territ\u00f3rios, os grandes bar\u00f5es do tr\u00e1fico de armas e drogas convivem muito bem nos governos e nos espa\u00e7os de poder. Lembremos que at\u00e9 em avi\u00f5es da FAB, no governo Bolsonaro, transportava-se coca\u00edna para o tr\u00e1fico internacional.<\/p>\n<p>A chamada \u201cguerra \u00e0s drogas\u201d \u00e9 a desculpa para assassinar crian\u00e7as, jovens, mulheres e idosos pretos das periferias. Vivemos a criminaliza\u00e7\u00e3o da pobreza e um processo de naturaliza\u00e7\u00e3o da viol\u00eancia e desumaniza\u00e7\u00e3o desses corpos e territ\u00f3rios. S\u00e3o d\u00e9cadas e d\u00e9cadas de \u201copera\u00e7\u00f5es\u201d invadindo o morro, ocupa\u00e7\u00e3o militar das favelas, tropas aterrorizando as baixadas e vielas e s\u00f3 quem perde \u00e9 o povo trabalhador e a juventude negra. E tudo isso foi aprofundado pela Lei de Drogas, sancionada nos governos anteriores do PT, que somente ampliaram o encarceramento do povo negro.<\/p>\n<p><strong>Na faixa de gaza e nas comunidades do Rio a pr\u00e1tica \u00e9 a mesma<\/strong><\/p>\n<p>Hoje vivemos uma incurs\u00e3o do nazisionismo israelense na faixa de Gaza com o objetivo de exterminar o povo palestino. Pois bem a PM do Rio n\u00e3o s\u00f3 compra armas e equipamentos de Israel como recebe treinamento dos mesmos que h\u00e1 d\u00e9cadas assassinam crian\u00e7as e jovens na faixa de Gaza e Cisjord\u00e2nia. N\u00e3o \u00e9 surpresa que como na palestina a pr\u00e1tica da pol\u00edcia do Rio tamb\u00e9m \u00e9 a mesma, pois as armas que matam em Gaza s\u00e3o as mesmas que matam pobres e negros nas comunidades do Rio de janeiro. Por isso que cresce a press\u00e3o para que o governo Lula rompa todas as rela\u00e7\u00f5es com Israel porque n\u00e3o se pode manter qualquer tipo de acordo com um Estado genocida.<\/p>\n<p><strong>Mobilizar por justi\u00e7a para Herus Mendes<\/strong><\/p>\n<p>Moradores da comunidade Santo Amaro fizeram um ato na manh\u00e3 de 07\/06 e est\u00e3o convocando um pr\u00f3ximo para o dia 08\/06. Esse \u00e9 o caminho a ser tomado para que mais um crime cometido pela pol\u00edcia n\u00e3o seja impune. Por isso \u00e9 fundamental que as organiza\u00e7\u00f5es de direitos humanos e dos movimentos sociais e sindicais estejam na linha de frente da justi\u00e7a para Herus e construam lutas. Exigimos investiga\u00e7\u00e3o, justi\u00e7a e a pris\u00e3o para os respons\u00e1veis por esse crime b\u00e1rbaro e indeniza\u00e7\u00e3o para a fam\u00edlia de Heron.<\/p>\n<p><strong>Por mais seguran\u00e7a para os trabalhadores: Desmantelar os aparatos repressivos<\/strong><\/p>\n<p>Para um projeto real de seguran\u00e7a para a classe trabalhadora \u00e9 necess\u00e1rio unificar as lutas por justi\u00e7a contra a viol\u00eancia policial e as pautas da classe trabalhadora. Exigir com isso o desmantelamento das PMs em todo o pa\u00eds e um plano de investimento real nas cidades para garantir emprego e moradia.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Chega da matan\u00e7a da pol\u00edcia O Bope do Rio de Janeiro realizou uma opera\u00e7\u00e3o na comunidade Santo Amaro na Gl\u00f3ria e matou o jovem Herus Guimar\u00e3es Mendes, de 24 anos. Mais uma a\u00e7\u00e3o criminosa da pol\u00edcia do governador da extrema direita, Cl\u00e1udio Castro (PL) que<\/p>\n","protected":false},"author":1,"featured_media":17306,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5,103],"tags":[],"class_list":["post-17305","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nacional","category-negros-e-negras"],"_links":{"self":[{"href":"https:\/\/www.cstuit.com\/home\/wp-json\/wp\/v2\/posts\/17305","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.cstuit.com\/home\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cstuit.com\/home\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cstuit.com\/home\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cstuit.com\/home\/wp-json\/wp\/v2\/comments?post=17305"}],"version-history":[{"count":0,"href":"https:\/\/www.cstuit.com\/home\/wp-json\/wp\/v2\/posts\/17305\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.cstuit.com\/home\/wp-json\/wp\/v2\/media\/17306"}],"wp:attachment":[{"href":"https:\/\/www.cstuit.com\/home\/wp-json\/wp\/v2\/media?parent=17305"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cstuit.com\/home\/wp-json\/wp\/v2\/categories?post=17305"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cstuit.com\/home\/wp-json\/wp\/v2\/tags?post=17305"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}