

	{"id":17382,"date":"2025-06-24T16:51:56","date_gmt":"2025-06-24T19:51:56","guid":{"rendered":"https:\/\/www.cstuit.com\/home\/?p=17382"},"modified":"2025-06-30T18:39:45","modified_gmt":"2025-06-30T21:39:45","slug":"declaracao-conjunta-condenamos-o-ataque-sionista-estadunidense-contra-o-ira-defendamos-o-ira","status":"publish","type":"post","link":"https:\/\/www.cstuit.com\/home\/2025\/06\/24\/declaracao-conjunta-condenamos-o-ataque-sionista-estadunidense-contra-o-ira-defendamos-o-ira\/","title":{"rendered":"Declara\u00e7\u00e3o conjunta: condenamos o ataque sionista-estadunidense contra o Ir\u00e3! Defendamos o Ir\u00e3!"},"content":{"rendered":"<p><img decoding=\"async\" class=\"alignnone size-medium wp-image-17404\" src=\"https:\/\/www.cstuit.com\/home\/wp-content\/uploads\/2025\/06\/declara-ataques-usa-israel-ao-ira-pt2.jpg\" alt=\"\" width=\"100%\" height=\"auto\" srcset=\"https:\/\/www.cstuit.com\/home\/wp-content\/uploads\/2025\/06\/declara-ataques-usa-israel-ao-ira-pt2.jpg 1080w, https:\/\/www.cstuit.com\/home\/wp-content\/uploads\/2025\/06\/declara-ataques-usa-israel-ao-ira-pt2-300x201.jpg 300w, https:\/\/www.cstuit.com\/home\/wp-content\/uploads\/2025\/06\/declara-ataques-usa-israel-ao-ira-pt2-1024x685.jpg 1024w, https:\/\/www.cstuit.com\/home\/wp-content\/uploads\/2025\/06\/declara-ataques-usa-israel-ao-ira-pt2-768x513.jpg 768w, https:\/\/www.cstuit.com\/home\/wp-content\/uploads\/2025\/06\/declara-ataques-usa-israel-ao-ira-pt2-600x401.jpg 600w, https:\/\/www.cstuit.com\/home\/wp-content\/uploads\/2025\/06\/declara-ataques-usa-israel-ao-ira-pt2-210x140.jpg 210w, https:\/\/www.cstuit.com\/home\/wp-content\/uploads\/2025\/06\/declara-ataques-usa-israel-ao-ira-pt2-272x182.jpg 272w, https:\/\/www.cstuit.com\/home\/wp-content\/uploads\/2025\/06\/declara-ataques-usa-israel-ao-ira-pt2-720x480.jpg 720w\" sizes=\"(max-width: 1080px) 100vw, 1080px\" \/><\/p>\n<p><em>Declara\u00e7\u00e3o da LIT-QI, UIT-QI e CCRI, 22 de junho de 2025.<\/em><\/p>\n<p>Em 13 de junho, Israel lan\u00e7ou outra guerra no Oriente M\u00e9dio. At\u00e9 o momento, matou quase 600 pessoas e destruiu in\u00fameros edif\u00edcios. Em resposta, o Ir\u00e3 retaliou e lan\u00e7ou v\u00e1rios m\u00edsseis contra o Estado colonizador. Nove dias depois, o ultra-direitista Donald Trump, em nome do imperialismo ianque, juntou-se \u00e0 guerra e atacou tr\u00eas instala\u00e7\u00f5es nucleares com bombas GBU-57 \u201cbunker buster&#8221; [\u201cdestruidora de bunkers&#8221;], as armas n\u00e3o nucleares mais poderosas do mundo. Enquanto Trump afirma triunfantemente que &#8220;as principais instala\u00e7\u00f5es de enriquecimento nuclear do Ir\u00e3 foram completamente destru\u00eddas&#8221;, as autoridades iranianas afirmam que os danos \u00e0s instala\u00e7\u00f5es nucleares foram limitados.<\/p>\n<p>O ataque sionista-estadunidense ao Ir\u00e3 \u00e9 uma continua\u00e7\u00e3o da longa agress\u00e3o de Israel e dos Estados Unidos contra os povos \u00e1rabes e mu\u00e7ulmanos do Oriente M\u00e9dio. Desde a cria\u00e7\u00e3o de Israel em 1948, o Estado sionista expulsou a popula\u00e7\u00e3o palestina de sua terra natal (a Nakba) e lan\u00e7ou in\u00fameras guerras contra todos os pa\u00edses vizinhos. O conflito atual ocorre no contexto da guerra genocida que o Estado sionista est\u00e1 travando contra o povo palestino em Gaza. Al\u00e9m disso, Israel tem atacado repetidamente a S\u00edria e o L\u00edbano e ocupado partes desses pa\u00edses.<\/p>\n<p>Da mesma forma, o imperialismo estadunidense tem um longo hist\u00f3rico de agress\u00f5es no Oriente M\u00e9dio, desde o L\u00edbano na d\u00e9cada de 1980 at\u00e9 a ocupa\u00e7\u00e3o do Afeganist\u00e3o e do Iraque.<\/p>\n<p>Condenamos essa nova guerra de agress\u00e3o de Israel e dos Estados Unidos e apoiamos os contra-ataques do Ir\u00e3. Fazemos isso porque esses contra-ataques s\u00e3o uma express\u00e3o da luta dos povos \u00e1rabes e mu\u00e7ulmanos contra o enclave militar do imperialismo, o Estado de Israel, que s\u00f3 pode ser mantido por meio de agress\u00f5es e ataques militares permanentes. Nesse conflito, estamos do lado militar do Ir\u00e3 e contra o monstro sionista-estadunidense.<\/p>\n<p>Ao mesmo tempo, mantemos nossa total independ\u00eancia pol\u00edtica diante do regime dos mul\u00e1s. Sempre apoiamos os protestos das massas iranianas contra a ditadura burguesa e teocr\u00e1tica, que governa despoticamente o pa\u00eds.<\/p>\n<p>O caminho para a vit\u00f3ria contra os agressores sionistas\/imperialistas passa pelas massas \u00e1rabes e mu\u00e7ulmanas, que apoiam a Palestina em sua luta contra o Estado de Israel e devem promover uma nova Primavera \u00c1rabe. Ou seja, uma revolu\u00e7\u00e3o que enfrente os pr\u00f3prios governos reacion\u00e1rios na regi\u00e3o. \u00c9 igualmente necess\u00e1rio fomentar a solidariedade internacional com a Palestina, e agora com o Ir\u00e3, nos pa\u00edses imperialistas.<\/p>\n<p>\u00c9 por isso que apelamos a todos os socialistas, anti-imperialistas e democratas para que se unam \u00e0s atividades de solidariedade internacional para deter o monstro sionista, que\u00a0 massacra os povos \u00e1rabes e mu\u00e7ulmanos. Denunciamos os &#8220;socialistas&#8221; que se recusam a defender o Ir\u00e3. Os socialistas devem unir-se em defesa do Ir\u00e3 e para derrotar o agressor sionista\/imperialista!<\/p>\n<p>Convocamos os povos do mundo a se mobilizarem para repudiar a agress\u00e3o militar contra o Ir\u00e3, liderada pelos criminosos Trump e Netanyahu. Apelamos \u00e0 mais ampla unidade de a\u00e7\u00e3o para derrot\u00e1-los. Dessa forma, tamb\u00e9m contribuiremos para a luta heroica do povo palestino, para p\u00f4r fim \u00e0 limpeza \u00e9tnica e ao genoc\u00eddio sionista e alcan\u00e7ar uma Palestina livre, do rio ao mar.<\/p>\n<ul>\n<li><strong>Defender o Ir\u00e3, derrotar Israel e o imperialismo estadunidense!<\/strong><\/li>\n<li><strong>Pela expuls\u00e3o das for\u00e7as estadunidenses do Oriente M\u00e9dio!<\/strong><\/li>\n<li><strong>Pela vit\u00f3ria da heroica resist\u00eancia palestina!<\/strong><\/li>\n<li><strong>Por um movimento global de boicote contra o Estado terrorista e de apartheid de Israel!<\/strong><\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<p><em><strong>Signat\u00e1rios:<\/strong><\/em><\/p>\n<ul>\n<li>Liga Internacional dos Trabalhadores \u2013 Quarta Internacional (LIT-QI, <a href=\"https:\/\/www.litci.org\">www.litci.org<\/a>)<\/li>\n<li>Unidade Internacional de Trabalhadoras e Trabalhadores \u2013 Quarta Internacional (UIT-QI, <a href=\"https:\/\/www.litci.org\">www.uit-ci.org<\/a>)<\/li>\n<li>Corrente Comunista Revolucion\u00e1ria Internacional (CCRI, <a href=\"https:\/\/www.thecommunists.net\">www.thecommunists.net<\/a>)<\/li>\n<\/ul>\n<p><em>P.S.: convidamos as organiza\u00e7\u00f5es que apoiam tais posi\u00e7\u00f5es a se juntarem a essa declara\u00e7\u00e3o e \u00e0 campanha.<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Declara\u00e7\u00e3o da LIT-QI, UIT-QI e CCRI, 22 de junho de 2025. Em 13 de junho, Israel lan\u00e7ou outra guerra no Oriente M\u00e9dio. At\u00e9 o momento, matou quase 600 pessoas e destruiu in\u00fameros edif\u00edcios. Em resposta, o Ir\u00e3 retaliou e lan\u00e7ou v\u00e1rios m\u00edsseis contra o Estado<\/p>\n","protected":false},"author":1,"featured_media":17405,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[6],"tags":[],"class_list":["post-17382","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-internacional"],"_links":{"self":[{"href":"https:\/\/www.cstuit.com\/home\/wp-json\/wp\/v2\/posts\/17382","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.cstuit.com\/home\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cstuit.com\/home\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cstuit.com\/home\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cstuit.com\/home\/wp-json\/wp\/v2\/comments?post=17382"}],"version-history":[{"count":0,"href":"https:\/\/www.cstuit.com\/home\/wp-json\/wp\/v2\/posts\/17382\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.cstuit.com\/home\/wp-json\/wp\/v2\/media\/17405"}],"wp:attachment":[{"href":"https:\/\/www.cstuit.com\/home\/wp-json\/wp\/v2\/media?parent=17382"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cstuit.com\/home\/wp-json\/wp\/v2\/categories?post=17382"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cstuit.com\/home\/wp-json\/wp\/v2\/tags?post=17382"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}