

	{"id":8695,"date":"2021-10-13T12:49:04","date_gmt":"2021-10-13T12:49:04","guid":{"rendered":"https:\/\/www.cstuit.com\/home\/?p=8695"},"modified":"2021-10-13T12:49:49","modified_gmt":"2021-10-13T12:49:49","slug":"argentina-derrota-do-governo-e-grande-eleicao-da-frente-de-esquerda","status":"publish","type":"post","link":"https:\/\/www.cstuit.com\/home\/2021\/10\/13\/argentina-derrota-do-governo-e-grande-eleicao-da-frente-de-esquerda\/","title":{"rendered":"Argentina: derrota do governo e grande elei\u00e7\u00e3o da Frente de Esquerda"},"content":{"rendered":"<p>&nbsp;<\/p>\n<p><strong>\u00a0<\/strong><\/p>\n<p><em>Os resultados das elei\u00e7\u00f5es nas PASO (prim\u00e1rias argentinas) confirmaram uma derrota retumbante do governo peronista da Frente de Todos. A outra novidade foi a grande elei\u00e7\u00e3o da Frente de Esquerda \u2013 Unidade (FIT-U), que superou a marca do milh\u00e3o de votos e foi a terceira for\u00e7a nacional. Com a unidade da esquerda estar\u00edamos conseguindo tr\u00eas cadeiras no Congresso Nacional, batalhando por outra em Jujuy e conquistando v\u00e1rios parlamentares na CABA (cidade de Buenos Aires) e na Prov\u00edncia de Buenos Aires. Trata-se de um resultado que fortalece a luta por uma alternativa pol\u00edtica da classe trabalhadora contra os pol\u00edticos tradicionais que v\u00eam governando para os de cima.<\/em><\/p>\n<p><em>\u00a0<\/em><\/p>\n<p>por <strong>Juan Carlos Giordano<\/strong>, deputado nacional pela Izquierda Socialista, partido integrante da FIT Unidad<\/p>\n<p>&nbsp;<\/p>\n<p>A p\u00e9rola do domingo parecia que ia ser o eleitor com cara de capincho\/capivara em Nordelta, at\u00e9 que se conheceram os primeiros resultados. Tudo mudou abruptamente, contradizendo as pesquisas e a boca de urna. O terremoto foi quando se soube que a Frente de Todos, na estrat\u00e9gica prov\u00edncia de Buenos Aires, na qual vinha de uma vit\u00f3ria de quase 50% em 2019 e agora se dizia que iria sobressair por 4 ou 5 pontos, perdeu de forma acachapante, com apenas 16% de seu volume eleitoral (2 milh\u00f5es e meio de votos). A partir da\u00ed, foi s\u00f3 ladeira abaixo.<\/p>\n<p>O governo encabe\u00e7ado por Alberto Fern\u00e1ndez e Cristina perdeu em 16 das 24 prov\u00edncias, sendo que havia ganhado em 19 apenas dois anos atr\u00e1s. Desta vez, ganhou apenas em 6, sendo as menos povoadas do pa\u00eds. O presidente havia dito que esta elei\u00e7\u00e3o iria plebiscitar sua gest\u00e3o, mas a realidade foi que 70% votou contra ele. Deu-se um enorme voto castigo. O governo recebeu um \u201ccruzado de direita\u201d, como disse um jornalista oficial, que teve impacto direto nas figuras do presidente, Cristina Fern\u00e1ndez, Kicillof, Sergio Massa, M\u00e1ximo Kirchner e na burocracia sindical que apoiou o governo.<\/p>\n<p>Todo o peronismo perdeu, ningu\u00e9m se salvou. Com o dado categ\u00f3rico da derrota de Alicia Kirchner em Santa Cruz e derrotas em outras prov\u00edncias governadas pelo peronismo, como Entre R\u00edos, Chaco, La Pampa e Chubut. Massa perdeu em Tigre e tamb\u00e9m na mencionada Chubut, governada por seu amigo Arcioni. Perderam munic\u00edpios sob controle de La C\u00e1mpora, como Quilmes, e tamb\u00e9m prov\u00edncias de todas as cores do peronismo, como em San Luis com os Sa\u00e1 ou C\u00f3rdoba com Schiaretti. At\u00e9 Randazzo ficou atr\u00e1s da FIT Unidade, assim como Guillermo Moreno, que nem passou as PASO.<\/p>\n<p>Passou-se de um peronismo unido, que lhes permitiu ganhar as elei\u00e7\u00f5es de 2019, a uma derrota em apenas dois anos, mostrando sua crise e abandono por uma base oper\u00e1ria e popular. \u201cSou peronista, mas o governo me decepcionou. Por isso, votei em Del Ca\u00f1o\u201d, disse um trabalhador consultado pela m\u00eddia no dia seguinte da elei\u00e7\u00e3o.<\/p>\n<p>O que houve? Foi um enorme voto castigo contra o governo e outras express\u00f5es de rep\u00fadio e exaust\u00e3o, como os 2 milh\u00f5es e meio que v\u00e3o foram votar (quase 10% mais que nas PASO de 2019), ou o milh\u00e3o e meio que votou em branco ou anulou. \u201cO grande problema foi o voto no peronismo. \u00c9 evidente que houve uma massa de eleitores da FDT que n\u00e3o foi votar. E n\u00e3o o fez por bronca, por descontentamento, porque n\u00e3o recebeu nenhuma das assist\u00eancias que houve diante da Covid-19, porque perdeu seu trabalho\u201d, apontou Roberto Bacman (P\u00e1gina21, 14\/09). A isso h\u00e1 que agregar outra massa de votantes que antes apoiava o peronismo e agora o abandonou de uma ou outra forma. Quase 5 milh\u00f5es que haviam votado na Frente de Todos em 2019 o deixaram de fazer em 2021. A vota\u00e7\u00e3o do governo se foi.<\/p>\n<p>A Frente de Todos vinha culpando Macri e a pandemia por todos os problemas, mas usou esse discurso para aplicar o ajuste aos aposentados, retirou direitos, manteve a infla\u00e7\u00e3o anual em 51%, o que devora os sal\u00e1rios, e dedicou-se a pagar pontualmente a d\u00edvida externa enquanto a fome e a pobreza crescem, agravando os males sociais. A isso h\u00e1 que somar a indigna\u00e7\u00e3o popular diante da foto de Olivos ou a Vacina\u00e7\u00e3o VIP, entre outros cart\u00f5es-postais que pareciam da era macrista. Esse descontentamento pegou n\u00e3o apenas nas camadas m\u00e9dias, mas p\u00f4de ser verificado nos bairros oper\u00e1rios e populares, onde muitos acabaram votando na FIT Unidade.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>O voto na direita n\u00e3o \u00e9 um \u201ccheque em branco\u201d<\/strong><\/p>\n<p><strong>\u00a0<\/strong><\/p>\n<p>N\u00e3o se deu uma grande polariza\u00e7\u00e3o nessa elei\u00e7\u00e3o, o que permitiu que surgissem outras op\u00e7\u00f5es e que, nesse contexto, se fortalecesse a Frente de Esquerda &#8211; Unidade. Parte da ruptura e descontentamento com a Frente de Todos foi capitalizada eleitoralmente pela oposi\u00e7\u00e3o patronal de direita, do Juntos pela Mudan\u00e7a, crescendo em torno de um milh\u00e3o de votos nesta oportunidade, ainda que em porcentagem mantenham o 40% das elei\u00e7\u00f5es passadas.<\/p>\n<p>Em suas listas, expressaram-se as batalhas internas que v\u00eam desde a derrota eleitoral de 2019 e seus reposicionamentos visando a elei\u00e7\u00e3o presidencial de 2023. O PRO escondeu Macri de quase toda a campanha, e ele nem sequer falou no ato onde se anunciaram os resultado. Houve v\u00e1rias listas em C\u00f3rdoba e em Santa Fe e tr\u00eas na CABA. A UCR tentou se diferenciar para tentar se fortalecer e ter mais protagonismo na alian\u00e7a e teve um resultado desigual. O angelocista Mario Negri, por exemplo, apoiado por Macri, perdeu com Luis Juez em C\u00f3rdoba, este \u00faltimo apoiado por Patricia Bullrich e Losteau, expressando a crise em suas posturas. Os radicais buscaram uma \u201ccara nova\u201d em Buenos Aires com Manes, como um adiantamento de que querem brigar pela f\u00f3rmula presidencial para 2023 com o macrismo. A isso se postulam tamb\u00e9m Gerardo Morales e Alfredo Cornejo. Mas, por hora, saiu fortalecida a \u201cnova equipe\u201d do PRO, com Larreta, Santilli e Vidal, se bem que tiveram que mudar seu discurso ainda mais para a direita em um \u00faltimo impulso da campanha, pressionados tanto por Patricia Bullrich e L\u00f3pez Murphy dentro de sua pr\u00f3pria for\u00e7a, como tamb\u00e9m por Milei de fora.<\/p>\n<p>O voto no Juntos pela Mudan\u00e7a, definitivamente, n\u00e3o significa um cheque em branco e nem uma esperan\u00e7a de que seu retorno ao poder seja uma sa\u00edda para o povo trabalhador, como demonstraram os quatro anos onde governaram com tarifa\u00e7os e um forte endividamento. Compreendemos a indigna\u00e7\u00e3o que h\u00e1 contra o governo atual, mas seguimos insistindo com os trabalhadores e jovens que para enfrentar o peronismo kirchnerista n\u00e3o est\u00e1 correto votar no macrismo e seus aliados da direita que governaram com ajuste e pobreza. Afirmamos que h\u00e1 outra alternativa, a esquerda que se une, que nunca governou e que enfrentou de maneira consequente todos os governos do ajuste.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>O \u201cfen\u00f4meno\u201d Milei<\/strong><\/p>\n<p><strong>\u00a0<\/strong><\/p>\n<p>Os pol\u00edticos capitalistas tradicionais foram t\u00e3o desastrosos que diante da indigna\u00e7\u00e3o contra seus governos jogaram \u00e1gua no moinho para que aparecessem personagens neofascistas como Javier Milei, que obteve 13% na CABA. Milei aparece como representante da ultradireita, j\u00e1 que Biondini, G\u00f3mez Centuri\u00f3n e Cynthia Hotton n\u00e3o passaram as PASO. Milei lembra o que ocorreu com Bolsonaro no Brasil diante da decep\u00e7\u00e3o com o PT de Lula ou com a direita do Vox em Madrid, ap\u00f3s os desastres do Partido Socialista e do Podemos. Sua lista \u201cA Liberdade Avan\u00e7a\u201d recolhe o voto de setores de direita (que culpam Macri por ser t\u00edmido na aplica\u00e7\u00e3o do ajuste); um setor juvenil de direita contra o \u201ccomunismo\u201d (assim Milei acusa o peronismo e at\u00e9 Larreta, algo c\u00f4mico) e outro setor confuso que faz eco de seu discurso antissistema, contra a \u201ccasta pol\u00edtica\u201d. Haver\u00e1 que ver se esse personagem cresce ou se vai desinflar no ritmo que v\u00e1 revelando sua verdadeira cara, que n\u00e3o \u00e9 mais do que a cara de um maior ajuste, atacando as liberdades democr\u00e1ticas, cerceando os direitos das mulheres ou negando as mudan\u00e7as clim\u00e1ticas. Seu aval ao governo peronista de Menem e Cavallo que destruiu o pa\u00eds mostra que sua \u201cliberdade\u201d \u00e9 para que a classe capitalista siga com o roubo salarial, destruindo as leis trabalhistas e curvando o pa\u00eds ainda mais diante do imperialismo.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>A unidade da esquerda foi premiada com uma grande elei\u00e7\u00e3o em todo o pa\u00eds<\/strong><\/p>\n<p><strong>\u00a0<\/strong><\/p>\n<p>A outra novidade e surpresa eleitoral (que a m\u00eddia n\u00e3o p\u00f4de ocultar) foi a grande elei\u00e7\u00e3o da Frente de Esquerda \u2013 Unidade, com a Lista 1A (PTS, PO e Izquierda Socialista) encabe\u00e7ada por Nicol\u00e1s Del Ca\u00f1o na prov\u00edncia de Buenos Aires e Myriam Bregman na Cidade de Buenos Aires. A FIT Unidade fez a melhor elei\u00e7\u00e3o desde sua forma\u00e7\u00e3o h\u00e1 10 anos, l\u00e1 por 2011. Naquela oportunidade fez meio milh\u00e3o de votos, e agora superou o milh\u00e3o (1.040.380 votos). Foi a terceira for\u00e7a nacional e na estrat\u00e9gica prov\u00edncia de Buenos Aires superou o direitista Espert e Randazzo.<\/p>\n<p>A FIT Unidade conseguiu vota\u00e7\u00f5es extraordin\u00e1rias. 23, 31% em Jujuy; 9,41% em Chubut; 7,85% em Santa Cruz; 7,90% em Neuqu\u00e9n; 6,89% em San Juan; 6,2% em CABA; 5,2% na Prov\u00edncia de Buenos Aires; 5,08% em La Rioja; 4,3% em C\u00f3rdoba, entre muitos outros bons resultados. Em San Juan, por exemplo, passou de 1,52% em 2019 para o vitorioso 6,89% atual. Em Gonz\u00e1lez Cat\u00e1n, La Matanza, para verean\u00e7a fez 8,47% e 8,78% em Merlo. Isso mostra que o voto na FIT se nutriu da ruptura de amplos setores oper\u00e1rios e populares com o peronismo.<\/p>\n<p>Com essa vota\u00e7\u00e3o, a FIT Unidade estaria conseguindo 3 cadeiras no Congresso Nacional (duas por Buenos Aires e uma pela CABA), est\u00e1 brigando por outra em Jujuy e conquistou v\u00e1rias e v\u00e1rios parlamentares na CABA e na terceira Se\u00e7\u00e3o eleitoral da prov\u00edncia de Buenos Aires. Bancadas que v\u00e3o ter rotatividade entre os tr\u00eas partidos fundadores da Frente de Esquerda (PTS, PO e Izquierda Socialista). Deputadas e deputados que seguir\u00e3o sendo a voz da classe trabalhadora, das mulheres e da juventude, defendendo o programa de fundo da Frente de Esquerda.<\/p>\n<p>A FIT Unidade \u00e9 a express\u00e3o eleitoral do crescimento das lutadoras, dos lutadores e da esquerda no movimento oper\u00e1rio, no movimento de mulheres, das dissid\u00eancias, da juventude explorada, vizinhos e setores populares contra a fome, a pobreza e o saque e a contamina\u00e7\u00e3o da megaminera\u00e7\u00e3o (como se deu em prov\u00edncias onde ocorreram mobiliza\u00e7\u00f5es importantes sobre o tema). Crescimento eleitoral que se deu apesar de existir uma esquerda que segue dividindo, como Luis Zamora em CABA. Ou Casta\u00f1eira do Novo MAS e Pol\u00edtica Oper\u00e1ria, com Ramal e Altamira, que n\u00e3o passaram para as elei\u00e7\u00f5es gerais por n\u00e3o superar o 1,5% necess\u00e1rio das PASO.<\/p>\n<p>Uma men\u00e7\u00e3o aparte merece ressaltar que a FIT Unidade, em seu interior, teve que enfrentar o fato de que o MST de Bodart e Celeste Fierro dividiram, competindo com sua pr\u00f3pria lista, criando uma divis\u00e3o equivocada que causou confus\u00e3o. Apareceram nos canais de televis\u00e3o, confer\u00eancias de imprensa e atos de campanha criticando a FIT Unidade por seu suposto \u201csectarismo\u201d, quando se trata da maior unidade da esquerda que j\u00e1 conseguimos. Passadas as PASO, a FIT Unidade sair\u00e1 unidade para dar a batalha para fazer uma nova e grande elei\u00e7\u00e3o em novembro.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>As perspectivas<\/strong><\/p>\n<p><strong>\u00a0<\/strong><\/p>\n<p>O resultado eleitoral de rep\u00fadio ao governo \u00e9 uma express\u00e3o do que tamb\u00e9m vem se dando na Am\u00e9rica Latina. Os governos v\u00eam sendo repudiados nas urnas e nas ruas por aplicar os ajustes capitalistas, sejam de centrodireita, neofascistas, como Bolsonaro, ou os denominados \u201cnacionais e populares\u201d como o peronismo. O peronismo na Argentina, que escolheu seguir pelo caminho de ajuste para pagar uma d\u00edvida fraudulenta, teve agora esse rep\u00fadio eleitoral.<\/p>\n<p>O governo tentar\u00e1 relocalizar-se fazendo an\u00fancios eleitoreiros para procurar reverter um resultado adverso para novembro. Mas n\u00e3o \u00e9 certo que consiga, inclusive pode seguir perdendo mais votos. Suas promessas de trabalho ou sal\u00e1rio ser\u00e3o pulverizadas porque est\u00e3o dispostos a pactuar com o FMI com aval do Macrismo, de Milei e Espert. O espelho \u00e9 o Equador, que acaba de assinar um acordo com esse organismo em troca de um maior ajuste. O pr\u00f3prio governo j\u00e1 sabe que os males v\u00e3o seguir. Uma prova disso \u00e9 que o Or\u00e7amento de 2022 enviado ao Congresso prev\u00ea uma infla\u00e7\u00e3o de 34% para o ano que vem, o que seguramente vai ser muito maior, com sua consequente perda salarial e previdenci\u00e1ria.<\/p>\n<p>O voto castigo contra o governo e o fato da grande elei\u00e7\u00e3o da Frente de Esquerda &#8211; Unidade s\u00e3o um incentivo para que possamos construir uma alternativa pol\u00edtica dos trabalhadores, das mulheres e da juventude e da unidade da esquerda para lutar por uma sa\u00edda de fundo, no caminho para conseguir um governo dos que nunca governaram, as e os trabalhadores e a esquerda.<\/p>\n<p>Saudamos aqueles e aquelas que foram parte dessa grande vota\u00e7\u00e3o da FIT Unidade e os convocamos a se somarem nas fileiras da Izquierda Socialista, para fazer mais forte a unidade da esquerda e enfrentar mais organizados os desafios que vir\u00e3o.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>&nbsp; \u00a0 Os resultados das elei\u00e7\u00f5es nas PASO (prim\u00e1rias argentinas) confirmaram uma derrota retumbante do governo peronista da Frente de Todos. A outra novidade foi a grande elei\u00e7\u00e3o da Frente de Esquerda \u2013 Unidade (FIT-U), que superou a marca do milh\u00e3o de votos e foi<\/p>\n","protected":false},"author":2,"featured_media":8696,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[6],"tags":[],"class_list":["post-8695","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-internacional"],"_links":{"self":[{"href":"https:\/\/www.cstuit.com\/home\/wp-json\/wp\/v2\/posts\/8695","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.cstuit.com\/home\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cstuit.com\/home\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cstuit.com\/home\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cstuit.com\/home\/wp-json\/wp\/v2\/comments?post=8695"}],"version-history":[{"count":0,"href":"https:\/\/www.cstuit.com\/home\/wp-json\/wp\/v2\/posts\/8695\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.cstuit.com\/home\/wp-json\/wp\/v2\/media\/8696"}],"wp:attachment":[{"href":"https:\/\/www.cstuit.com\/home\/wp-json\/wp\/v2\/media?parent=8695"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cstuit.com\/home\/wp-json\/wp\/v2\/categories?post=8695"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cstuit.com\/home\/wp-json\/wp\/v2\/tags?post=8695"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}